{"id":4900,"date":"2020-06-12T12:00:00","date_gmt":"2020-06-12T10:00:00","guid":{"rendered":"https:\/\/my-cat.eu\/retrato-de-raza-gatos-persas\/"},"modified":"2020-06-19T18:33:53","modified_gmt":"2020-06-19T16:33:53","slug":"retrato-de-raza-gatos-persas","status":"publish","type":"post","link":"https:\/\/my-cat.eu\/es\/razas\/retrato-de-raza-gatos-persas\/","title":{"rendered":"Retrato de raza gatos persas"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Lesezeit: <\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">Minuten<\/span><\/span><div class=\"wp-block-ub-table-of-contents-block ub_table-of-contents\" id=\"ub_table-of-contents-871796a5-161e-40bc-ab4b-f5630fe49afa\" data-linktodivider=\"false\" data-showtext=\"show\" data-hidetext=\"hide\" data-scrolltype=\"auto\" data-enablesmoothscroll=\"false\" data-initiallyhideonmobile=\"false\" data-initiallyshow=\"true\"><div class=\"ub_table-of-contents-header-container\" style=\"\">\n\t\t\t<div class=\"ub_table-of-contents-header\" style=\"text-align: left; \">\n\t\t\t\t<div class=\"ub_table-of-contents-title\" style=\"\">Contenido<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div><div class=\"ub_table-of-contents-extra-container\" style=\"\">\n\t\t\t<div class=\"ub_table-of-contents-container ub_table-of-contents-1-column \">\n\t\t\t\t<ul style=\"\"><li style=\"\"><a href=\"https:\/\/my-cat.eu\/es\/razas\/retrato-de-raza-gatos-persas\/#0-historia-y-origen\" style=\"\">Historia y origen<\/a><\/li><li style=\"\"><a href=\"https:\/\/my-cat.eu\/es\/razas\/retrato-de-raza-gatos-persas\/#1-caracter%C3%ADsticas-de-la-carrera\" style=\"\">Caracter\u00edsticas de la carrera<\/a><\/li><li style=\"\"><a href=\"https:\/\/my-cat.eu\/es\/razas\/retrato-de-raza-gatos-persas\/#2-actitud-y-cuidado\" style=\"\">Actitud y cuidado<\/a><\/li><\/ul>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n\n\n<p>Los <a href=\"https:\/\/de.wikipedia.org\/wiki\/Perserkatze\" class=\"rank-math-link\" target=\"_blank\" rel=\"noopener\">gatos persas<\/a> son animales muy interesantes. Tienen un abrigo muy esponjoso. Sin embargo, esto tambi\u00e9n requiere mucho cuidado. Los gatos son muy tranquilos y por lo tanto parecen un poco flem\u00e1ticos. Con otros animales, ya sean gatos o incluso perros se llevan muy bien. Son reticentes con extra\u00f1os. Los gatos persas no muerden ni rascan. Los delicados e inteligentes se pueden mantener f\u00e1cilmente en los hogares con ni\u00f1os.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"0-historia-y-origen\">Historia y origen<\/h2>\n\n\n\n<p>Se cree que los gatos llegaron a Europa en el siglo XVI. Probablemente fueron tra\u00eddos por viajeros italianos de Persia. En ese momento, sin embargo, los animales no eran tan esponjosos como lo son hoy en d\u00eda. En Gran Breta\u00f1a, comenz\u00f3 la encrucijada de la raza. El primer esp\u00e9cimen fue desarrollado en 1880. Debido a la selecci\u00f3n, el pelaje de los gatos se volvi\u00f3 particularmente esponjoso y largo. La nariz se hizo mucho m\u00e1s peque\u00f1a que en los ancestros.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"1-caracter%C3%ADsticas-de-la-carrera\">Caracter\u00edsticas de la carrera<\/h2>\n\n\n\n<figure class=\"wp-block-gallery alignleft columns-1 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/my-cat.eu\/wp-content\/uploads\/2020\/05\/cat-2154726_1920.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"689\" src=\"https:\/\/my-cat.eu\/wp-content\/uploads\/2020\/05\/cat-2154726_1920-1024x689.jpg\" alt=\"Perserkatzen\" data-id=\"3062\" data-full-url=\"https:\/\/my-cat.eu\/wp-content\/uploads\/2020\/05\/cat-2154726_1920.jpg\" data-link=\"https:\/\/my-cat.eu\/?attachment_id=3062\" class=\"wp-image-3062\" title=\"\" srcset=\"https:\/\/my-cat.eu\/wp-content\/uploads\/2020\/05\/cat-2154726_1920-1024x689.jpg 1024w, https:\/\/my-cat.eu\/wp-content\/uploads\/2020\/05\/cat-2154726_1920-300x202.jpg 300w, https:\/\/my-cat.eu\/wp-content\/uploads\/2020\/05\/cat-2154726_1920-768x516.jpg 768w, https:\/\/my-cat.eu\/wp-content\/uploads\/2020\/05\/cat-2154726_1920-1536x1033.jpg 1536w, https:\/\/my-cat.eu\/wp-content\/uploads\/2020\/05\/cat-2154726_1920.jpg 1374w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>Los gatos pesan hasta 7 kg. La estupsnase peque\u00f1a y ancha es una caracter\u00edstica caracter\u00edstica de esta raza. Con el tiempo, se crearon dos especies. Uno se caracteriza por una nariz m\u00e1s peque\u00f1a y muy elevada. Estos se conocen como Ultra y se cr\u00edan en los EE.UU. El estilo cl\u00e1sico tiene una nariz larga y ligera.<\/p>\n\n\n\n<p>Los gatos persas tradicionales son criados en Europa. La raza se caracteriza por m\u00e1s de 100 tonos t\u00edpicos. Hay rubias, beige, rojas, grises, blancas o negras. El color de los ojos es igual de variado. De azul claro a naranja oscuro, cobre o dorado a verde. Los animales monocromos no deben mostrar sombras o cambios en el cuerpo. Los gatos suelen tener los llamados puntos de color. Estos son peque\u00f1os puntos en la cola, las patas o la cabeza.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"2-actitud-y-cuidado\">Actitud y cuidado<\/h2>\n\n\n\n<p>Estos animales son muy cari\u00f1osos y siempre quieren estar en compa\u00f1\u00eda de su guardi\u00e1n. Ya sea en el regazo o en los hombros. Est\u00e1n constantemente ronroneando. Est\u00e1n constantemente siguiendo a su propietario y no quieren estar solos. Edad independiente de los gatos les gusta <a href=\"https:\/\/my-cat.eu\/es\/entretenido-entrenamiento-clicker-con-gatos-para-el-juego-y-la-diversion\/\" class=\"rank-math-link\">jugar.<\/a> Por lo tanto, exigen una cantidad correspondiente de atenci\u00f3n de los seres humanos. Necesitan mucho entretenimiento para que se sientan c\u00f3modos. <\/p>\n\n\n\n<p>Prefieren quedarse en casa en su entorno familiar. No pueden vivir fuera de la casa o apartamento. Los gatos de esta raza generalmente tienen una confianza muy alta en los seres humanos. Cuando piden atenci\u00f3n, no la cortan. Luego se sientan junto a su due\u00f1o y lo observan atentamente. Los animales deben cepillarse todos los d\u00edas y ba\u00f1arse una vez a la semana debido a la piel intensiva en cuidados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Lesezeit: <\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">Minuten<\/span><\/span>Los gatos persas son animales muy interesantes. Tienen un abrigo muy esponjoso. Sin embargo, esto tambi\u00e9n requiere mucho cuidado. Los gatos son muy tranquilos y por lo tanto parecen un poco flem\u00e1ticos. Con otros animales, ya sean gatos o incluso perros se llevan muy bien. Son reticentes con extra\u00f1os. Los gatos persas no muerden ni [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4901,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[503],"tags":[553,586],"class_list":["post-4900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-razas","tag-gato-persa","tag-gatos-persas"],"featured_image_src":"https:\/\/my-cat.eu\/wp-content\/uploads\/2020\/05\/cat-1013103_1920.jpg","author_info":{"display_name":"Franklin","author_link":"https:\/\/my-cat.eu\/es\/author\/c-5624-wg\/"},"_links":{"self":[{"href":"https:\/\/my-cat.eu\/es\/wp-json\/wp\/v2\/posts\/4900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-cat.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-cat.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-cat.eu\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/my-cat.eu\/es\/wp-json\/wp\/v2\/comments?post=4900"}],"version-history":[{"count":0,"href":"https:\/\/my-cat.eu\/es\/wp-json\/wp\/v2\/posts\/4900\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/my-cat.eu\/es\/wp-json\/wp\/v2\/media\/4901"}],"wp:attachment":[{"href":"https:\/\/my-cat.eu\/es\/wp-json\/wp\/v2\/media?parent=4900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-cat.eu\/es\/wp-json\/wp\/v2\/categories?post=4900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-cat.eu\/es\/wp-json\/wp\/v2\/tags?post=4900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}